{"id":467,"date":"2019-10-18T08:33:41","date_gmt":"2019-10-18T08:33:41","guid":{"rendered":"http:\/\/ocidentaladventures.pt\/?page_id=467"},"modified":"2023-01-20T16:29:03","modified_gmt":"2023-01-20T16:29:03","slug":"actividades","status":"publish","type":"page","link":"https:\/\/ocidentaladventures.pt\/es\/actividades\/","title":{"rendered":"Actividades"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"467\" class=\"elementor elementor-467 elementor-12\">\n\t\t\t\t\t\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-74cbb78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74cbb78\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be5915a\" data-id=\"be5915a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fc1497 elementor-widget elementor-widget-shortcode\" data-id=\"7fc1497\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-541baac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"541baac\" data-element_type=\"section\">\r\n    <div class=\"elementor-container elementor-column-gap-no\">\r\n      <div class=\"elementor-row\">\r\n          <div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ccf3e7d\" data-id=\"ccf3e7d\" data-element_type=\"column\">\r\n            <div class=\"theiaStickySidebar elementor-column-wrap elementor-element-populated\">\r\n                <div class=\"elementor-widget-wrap\">\r\n                  <div class=\"elementor-element elementor-element-f4a76bb elementor-view-default elementor-widget elementor-widget-icon \" data-id=\"f4a76bb\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\r\n                      <div class=\"elementor-widget-container\">\r\n                        <div class=\"elementor-icon-wrapper textAlignCenter\">\r\n                            <div class=\"elementor-icon\">\r\n                              <i style=\"color:#0c3513\" aria-hidden=\"true\" class=\"fa-solid fa-tree\"><\/i>\t\t\t\r\n                            <\/div>\r\n                        <\/div>\r\n                      <\/div>\r\n                  <\/div>\r\n                  <div class=\"elementor-element elementor-element-422c634 elementor-widget elementor-widget-penci-fancy_heading\" data-id=\"422c634\" data-element_type=\"widget\" data-widget_type=\"penci-fancy_heading.default\">\r\n                      <div class=\"elementor-widget-container\">\r\n                        <div class=\"penci-fancy-heading penci-heading-text-center\">\r\n                            <div class=\"penci-fancy-heading-inner\">\r\n                              <h2 class=\"penci-heading-title fontWeight500\"><\/h2>\r\n                              <div class=\"penci-heading-content entry-content\">\r\n                                \r\n                              <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                      <\/div>\r\n                  <\/div>\r\n                <\/div>\r\n            <\/div>\r\n          <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/section>\r\n  <section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-b5aba68 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b5aba68\" data-element_type=\"section\">\r\n    <div class=\"elementor-container elementor-column-gap-no\">\r\n        <div class=\"elementor-row\">\r\n          <div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5180057\" data-id=\"5180057\" data-element_type=\"column\">\r\n              <div class=\"theiaStickySidebar elementor-column-wrap elementor-element-populated\">\r\n                <div class=\"elementor-widget-wrap\">\r\n                    <section class=\"penci-section penci-disSticky penci-structure-30 elementor-section elementor-inner-section elementor-element elementor-element-9c034f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c034f0\" data-element_type=\"section\">\r\n                      <div class=\"elementor-container elementor-column-gap-extended\">\r\n                          <div class=\"elementor-row\" style=\"display:flex; flex-flow:row wrap;\">\r\n                            <div class=\"penci-ercol-33 atividade_container_single penci-ercol-order-1 penci-sticky-sb penci-sidebarSC elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ad6dd3c\" data-id=\"ad6dd3c\" data-element_type=\"column\">\r\n        <div class=\"theiaStickySidebar elementor-column-wrap elementor-element-populated\">\r\n          <div class=\"elementor-widget-wrap\" style=\"display:flex; flex-flow:column;\">\r\n              <div class=\"atividadesContainerSingleImage elementor-element elementor-element-3df9721 elementor-widget elementor-widget-image\" data-id=\"3df9721\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n        <div class=\"preco\">\r\n        55.00\u20ac\r\n      <\/div>\r\n        <div class=\"elementor-widget-container\">\r\n            <div class=\"elementor-image\">\r\n              <img decoding=\"async\" src=\"https:\/\/ocidentaladventures.pt\/wp-content\/uploads\/2023\/01\/A7I03668-ARW_DxO_DeepPRIME-scaled.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" >\t\t\t\t\t\t\t\t\t\t\t\r\n            <\/div>\r\n        <\/div>\r\n      <\/div>\r\n              <div class=\"elementor-element elementor-element-bc89a85 elementor-widget elementor-widget-penci-fancy_heading\" data-id=\"bc89a85\" data-element_type=\"widget\" data-widget_type=\"penci-fancy_heading.default\" style=\"flex-grow:1;\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"penci-fancy-heading penci-heading-text-left\">\r\n                      <div class=\"penci-fancy-heading-inner\">\r\n                          <h2 class=\"penci-heading-title\">Bautismo de Canyoning<\/h2>\r\n                          <div class=\"penci-heading-content entry-content\">\r\n                            Una buena opci\u00f3n para aquellos que buscan diversi\u00f3n en un lugar magn\u00edfico de la costa&hellip;\r\n                          <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"elementor-element elementor-element-9b598ac elementor-align-left elementor-widget elementor-widget-button\" data-id=\"9b598ac\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"elementor-button-wrapper\">\r\n                      <a href=\"https:\/\/ocidentaladventures.pt\/es\/atividade\/canyoning\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\r\n                      <span class=\"elementor-button-content-wrapper\">\r\n                      <span class=\"elementor-button-text\">Reservar<\/span>\r\n                      <\/span>\r\n                      <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n          <\/div>\r\n        <\/div>\r\n    <\/div><div class=\"penci-ercol-33 atividade_container_single penci-ercol-order-1 penci-sticky-sb penci-sidebarSC elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ad6dd3c\" data-id=\"ad6dd3c\" data-element_type=\"column\">\r\n        <div class=\"theiaStickySidebar elementor-column-wrap elementor-element-populated\">\r\n          <div class=\"elementor-widget-wrap\" style=\"display:flex; flex-flow:column;\">\r\n              <div class=\"atividadesContainerSingleImage elementor-element elementor-element-3df9721 elementor-widget elementor-widget-image\" data-id=\"3df9721\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n        <div class=\"preco\">\r\n        70.00\u20ac\r\n      <\/div>\r\n        <div class=\"elementor-widget-container\">\r\n            <div class=\"elementor-image\">\r\n              <img decoding=\"async\" src=\"https:\/\/ocidentaladventures.pt\/wp-content\/uploads\/2023\/01\/IMG_3684-scaled.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" >\t\t\t\t\t\t\t\t\t\t\t\r\n            <\/div>\r\n        <\/div>\r\n      <\/div>\r\n              <div class=\"elementor-element elementor-element-bc89a85 elementor-widget elementor-widget-penci-fancy_heading\" data-id=\"bc89a85\" data-element_type=\"widget\" data-widget_type=\"penci-fancy_heading.default\" style=\"flex-grow:1;\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"penci-fancy-heading penci-heading-text-left\">\r\n                      <div class=\"penci-fancy-heading-inner\">\r\n                          <h2 class=\"penci-heading-title\">Canyoning Ilh\u00e9us Inferior \u2013 (Nivel 1)<\/h2>\r\n                          <div class=\"penci-heading-content entry-content\">\r\n                            \u00bfEst\u00e1s listo para una aventura impresionante? Entonces ven a disfrutar de este barranquismo en un&hellip;\r\n                          <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"elementor-element elementor-element-9b598ac elementor-align-left elementor-widget elementor-widget-button\" data-id=\"9b598ac\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"elementor-button-wrapper\">\r\n                      <a href=\"https:\/\/ocidentaladventures.pt\/es\/atividade\/canyoning-ilheus-inferior\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\r\n                      <span class=\"elementor-button-content-wrapper\">\r\n                      <span class=\"elementor-button-text\">Reservar<\/span>\r\n                      <\/span>\r\n                      <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n          <\/div>\r\n        <\/div>\r\n    <\/div><div class=\"penci-ercol-33 atividade_container_single penci-ercol-order-1 penci-sticky-sb penci-sidebarSC elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ad6dd3c\" data-id=\"ad6dd3c\" data-element_type=\"column\">\r\n        <div class=\"theiaStickySidebar elementor-column-wrap elementor-element-populated\">\r\n          <div class=\"elementor-widget-wrap\" style=\"display:flex; flex-flow:column;\">\r\n              <div class=\"atividadesContainerSingleImage elementor-element elementor-element-3df9721 elementor-widget elementor-widget-image\" data-id=\"3df9721\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n        <div class=\"preco\">\r\n        110.00\u20ac\r\n      <\/div>\r\n        <div class=\"elementor-widget-container\">\r\n            <div class=\"elementor-image\">\r\n              <img decoding=\"async\" src=\"https:\/\/ocidentaladventures.pt\/wp-content\/uploads\/2023\/01\/IMG_3447-scaled.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" >\t\t\t\t\t\t\t\t\t\t\t\r\n            <\/div>\r\n        <\/div>\r\n      <\/div>\r\n              <div class=\"elementor-element elementor-element-bc89a85 elementor-widget elementor-widget-penci-fancy_heading\" data-id=\"bc89a85\" data-element_type=\"widget\" data-widget_type=\"penci-fancy_heading.default\" style=\"flex-grow:1;\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"penci-fancy-heading penci-heading-text-left\">\r\n                      <div class=\"penci-fancy-heading-inner\">\r\n                          <h2 class=\"penci-heading-title\">Canyoning Ilh\u00e9us M\u00e9dio \u2013 (Nivel 2)<\/h2>\r\n                          <div class=\"penci-heading-content entry-content\">\r\n                            Comenzamos esta aventura recorriendo una parte del sendero que une Ponta Delgada con Ponta Ruiva.&hellip;\r\n                          <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"elementor-element elementor-element-9b598ac elementor-align-left elementor-widget elementor-widget-button\" data-id=\"9b598ac\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"elementor-button-wrapper\">\r\n                      <a href=\"https:\/\/ocidentaladventures.pt\/es\/atividade\/canyoning-ilheus-medio\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\r\n                      <span class=\"elementor-button-content-wrapper\">\r\n                      <span class=\"elementor-button-text\">Reservar<\/span>\r\n                      <\/span>\r\n                      <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n          <\/div>\r\n        <\/div>\r\n    <\/div><div class=\"penci-ercol-33 atividade_container_single penci-ercol-order-1 penci-sticky-sb penci-sidebarSC elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ad6dd3c\" data-id=\"ad6dd3c\" data-element_type=\"column\">\r\n        <div class=\"theiaStickySidebar elementor-column-wrap elementor-element-populated\">\r\n          <div class=\"elementor-widget-wrap\" style=\"display:flex; flex-flow:column;\">\r\n              <div class=\"atividadesContainerSingleImage elementor-element elementor-element-3df9721 elementor-widget elementor-widget-image\" data-id=\"3df9721\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n        <div class=\"preco\">\r\n        160.00\u20ac\r\n      <\/div>\r\n        <div class=\"elementor-widget-container\">\r\n            <div class=\"elementor-image\">\r\n              <img decoding=\"async\" src=\"https:\/\/ocidentaladventures.pt\/wp-content\/uploads\/2026\/02\/IMG_6467-scaled.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" >\t\t\t\t\t\t\t\t\t\t\t\r\n            <\/div>\r\n        <\/div>\r\n      <\/div>\r\n              <div class=\"elementor-element elementor-element-bc89a85 elementor-widget elementor-widget-penci-fancy_heading\" data-id=\"bc89a85\" data-element_type=\"widget\" data-widget_type=\"penci-fancy_heading.default\" style=\"flex-grow:1;\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"penci-fancy-heading penci-heading-text-left\">\r\n                      <div class=\"penci-fancy-heading-inner\">\r\n                          <h2 class=\"penci-heading-title\">Canyoning Ilh\u00e9us M\u00e9dio + Inferior \u2013 (Nivel 3)<\/h2>\r\n                          <div class=\"penci-heading-content entry-content\">\r\n                            Iniciamos esta aventura recorriendo una parte del sendero que une Ponta Delgada con Ponta Ruiva.&hellip;\r\n                          <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"elementor-element elementor-element-9b598ac elementor-align-left elementor-widget elementor-widget-button\" data-id=\"9b598ac\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"elementor-button-wrapper\">\r\n                      <a href=\"https:\/\/ocidentaladventures.pt\/es\/atividade\/canyoning-ilheus-medio-inferior\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\r\n                      <span class=\"elementor-button-content-wrapper\">\r\n                      <span class=\"elementor-button-text\">Reservar<\/span>\r\n                      <\/span>\r\n                      <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n          <\/div>\r\n        <\/div>\r\n    <\/div><div class=\"penci-ercol-33 atividade_container_single penci-ercol-order-1 penci-sticky-sb penci-sidebarSC elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ad6dd3c\" data-id=\"ad6dd3c\" data-element_type=\"column\">\r\n        <div class=\"theiaStickySidebar elementor-column-wrap elementor-element-populated\">\r\n          <div class=\"elementor-widget-wrap\" style=\"display:flex; flex-flow:column;\">\r\n              <div class=\"atividadesContainerSingleImage elementor-element elementor-element-3df9721 elementor-widget elementor-widget-image\" data-id=\"3df9721\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n        <div class=\"preco\">\r\n        200.00\u20ac\r\n      <\/div>\r\n        <div class=\"elementor-widget-container\">\r\n            <div class=\"elementor-image\">\r\n              <img decoding=\"async\" src=\"https:\/\/ocidentaladventures.pt\/wp-content\/uploads\/2023\/01\/IMG_6855-scaled.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" >\t\t\t\t\t\t\t\t\t\t\t\r\n            <\/div>\r\n        <\/div>\r\n      <\/div>\r\n              <div class=\"elementor-element elementor-element-bc89a85 elementor-widget elementor-widget-penci-fancy_heading\" data-id=\"bc89a85\" data-element_type=\"widget\" data-widget_type=\"penci-fancy_heading.default\" style=\"flex-grow:1;\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"penci-fancy-heading penci-heading-text-left\">\r\n                      <div class=\"penci-fancy-heading-inner\">\r\n                          <h2 class=\"penci-heading-title\">Canyoning Po\u00e7o do Bacalhau \u2013 (Nivel 4)<\/h2>\r\n                          <div class=\"penci-heading-content entry-content\">\r\n                            Algo sorprendente te est\u00e1 esperando, despu\u00e9s de superar varias ca\u00eddas de agua llegamos a la&hellip;\r\n                          <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"elementor-element elementor-element-9b598ac elementor-align-left elementor-widget elementor-widget-button\" data-id=\"9b598ac\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"elementor-button-wrapper\">\r\n                      <a href=\"https:\/\/ocidentaladventures.pt\/es\/atividade\/canyoning-poco-do-bacalhau\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\r\n                      <span class=\"elementor-button-content-wrapper\">\r\n                      <span class=\"elementor-button-text\">Reservar<\/span>\r\n                      <\/span>\r\n                      <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n          <\/div>\r\n        <\/div>\r\n    <\/div><div class=\"penci-ercol-33 atividade_container_single penci-ercol-order-1 penci-sticky-sb penci-sidebarSC elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ad6dd3c\" data-id=\"ad6dd3c\" data-element_type=\"column\">\r\n        <div class=\"theiaStickySidebar elementor-column-wrap elementor-element-populated\">\r\n          <div class=\"elementor-widget-wrap\" style=\"display:flex; flex-flow:column;\">\r\n              <div class=\"atividadesContainerSingleImage elementor-element elementor-element-3df9721 elementor-widget elementor-widget-image\" data-id=\"3df9721\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n        <div class=\"preco\">\r\n        220.00\u20ac\r\n      <\/div>\r\n        <div class=\"elementor-widget-container\">\r\n            <div class=\"elementor-image\">\r\n              <img decoding=\"async\" src=\"https:\/\/ocidentaladventures.pt\/wp-content\/uploads\/2024\/05\/CA6B991A-41F9-4DB0-8B51-EDA8915A88CB_1_105_c-1.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" >\t\t\t\t\t\t\t\t\t\t\t\r\n            <\/div>\r\n        <\/div>\r\n      <\/div>\r\n              <div class=\"elementor-element elementor-element-bc89a85 elementor-widget elementor-widget-penci-fancy_heading\" data-id=\"bc89a85\" data-element_type=\"widget\" data-widget_type=\"penci-fancy_heading.default\" style=\"flex-grow:1;\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"penci-fancy-heading penci-heading-text-left\">\r\n                      <div class=\"penci-fancy-heading-inner\">\r\n                          <h2 class=\"penci-heading-title\">Canyoning Barrosas<\/h2>\r\n                          <div class=\"penci-heading-content entry-content\">\r\n                            Desde tobog\u00e3s (escorregas naturais) a saltos para a \u00e1gua e encerrando este canyoning no mar&hellip;\r\n                          <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"elementor-element elementor-element-9b598ac elementor-align-left elementor-widget elementor-widget-button\" data-id=\"9b598ac\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"elementor-button-wrapper\">\r\n                      <a href=\"https:\/\/ocidentaladventures.pt\/es\/atividade\/canyoning-barrosas\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\r\n                      <span class=\"elementor-button-content-wrapper\">\r\n                      <span class=\"elementor-button-text\">Reservar<\/span>\r\n                      <\/span>\r\n                      <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n          <\/div>\r\n        <\/div>\r\n    <\/div><div class=\"penci-ercol-33 atividade_container_single penci-ercol-order-1 penci-sticky-sb penci-sidebarSC elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ad6dd3c\" data-id=\"ad6dd3c\" data-element_type=\"column\">\r\n        <div class=\"theiaStickySidebar elementor-column-wrap elementor-element-populated\">\r\n          <div class=\"elementor-widget-wrap\" style=\"display:flex; flex-flow:column;\">\r\n              <div class=\"atividadesContainerSingleImage elementor-element elementor-element-3df9721 elementor-widget elementor-widget-image\" data-id=\"3df9721\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n        <div class=\"preco\">\r\n        90.00\u20ac\r\n      <\/div>\r\n        <div class=\"elementor-widget-container\">\r\n            <div class=\"elementor-image\">\r\n              <img decoding=\"async\" src=\"https:\/\/ocidentaladventures.pt\/wp-content\/uploads\/2023\/01\/A7I03946-scaled.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" >\t\t\t\t\t\t\t\t\t\t\t\r\n            <\/div>\r\n        <\/div>\r\n      <\/div>\r\n              <div class=\"elementor-element elementor-element-bc89a85 elementor-widget elementor-widget-penci-fancy_heading\" data-id=\"bc89a85\" data-element_type=\"widget\" data-widget_type=\"penci-fancy_heading.default\" style=\"flex-grow:1;\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"penci-fancy-heading penci-heading-text-left\">\r\n                      <div class=\"penci-fancy-heading-inner\">\r\n                          <h2 class=\"penci-heading-title\">Tour Flores 360\u00ba<\/h2>\r\n                          <div class=\"penci-heading-content entry-content\">\r\n                            Pase el d\u00eda con nosotros y d\u00e9jese maravillar por las bellezas que la isla tiene&hellip;\r\n                          <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"elementor-element elementor-element-9b598ac elementor-align-left elementor-widget elementor-widget-button\" data-id=\"9b598ac\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"elementor-button-wrapper\">\r\n                      <a href=\"https:\/\/ocidentaladventures.pt\/es\/atividade\/tour-flores-360o\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\r\n                      <span class=\"elementor-button-content-wrapper\">\r\n                      <span class=\"elementor-button-text\">Reservar<\/span>\r\n                      <\/span>\r\n                      <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n          <\/div>\r\n        <\/div>\r\n    <\/div><div class=\"penci-ercol-33 atividade_container_single penci-ercol-order-1 penci-sticky-sb penci-sidebarSC elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ad6dd3c\" data-id=\"ad6dd3c\" data-element_type=\"column\">\r\n        <div class=\"theiaStickySidebar elementor-column-wrap elementor-element-populated\">\r\n          <div class=\"elementor-widget-wrap\" style=\"display:flex; flex-flow:column;\">\r\n              <div class=\"atividadesContainerSingleImage elementor-element elementor-element-3df9721 elementor-widget elementor-widget-image\" data-id=\"3df9721\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n        <div class=\"preco\">\r\n        60.00\u20ac\r\n      <\/div>\r\n        <div class=\"elementor-widget-container\">\r\n            <div class=\"elementor-image\">\r\n              <img decoding=\"async\" src=\"https:\/\/ocidentaladventures.pt\/wp-content\/uploads\/2023\/01\/A7I03950-scaled.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" >\t\t\t\t\t\t\t\t\t\t\t\r\n            <\/div>\r\n        <\/div>\r\n      <\/div>\r\n              <div class=\"elementor-element elementor-element-bc89a85 elementor-widget elementor-widget-penci-fancy_heading\" data-id=\"bc89a85\" data-element_type=\"widget\" data-widget_type=\"penci-fancy_heading.default\" style=\"flex-grow:1;\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"penci-fancy-heading penci-heading-text-left\">\r\n                      <div class=\"penci-fancy-heading-inner\">\r\n                          <h2 class=\"penci-heading-title\">Tour Lagunas y Cascadas<\/h2>\r\n                          <div class=\"penci-heading-content entry-content\">\r\n                            Venga a conocer el interior de nuestra hermosa isla, visitando nuestras 7 lagunas y luego&hellip;\r\n                          <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"elementor-element elementor-element-9b598ac elementor-align-left elementor-widget elementor-widget-button\" data-id=\"9b598ac\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"elementor-button-wrapper\">\r\n                      <a href=\"https:\/\/ocidentaladventures.pt\/es\/atividade\/tours\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\r\n                      <span class=\"elementor-button-content-wrapper\">\r\n                      <span class=\"elementor-button-text\">Reservar<\/span>\r\n                      <\/span>\r\n                      <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n          <\/div>\r\n        <\/div>\r\n    <\/div><div class=\"penci-ercol-33 atividade_container_single penci-ercol-order-1 penci-sticky-sb penci-sidebarSC elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ad6dd3c\" data-id=\"ad6dd3c\" data-element_type=\"column\">\r\n        <div class=\"theiaStickySidebar elementor-column-wrap elementor-element-populated\">\r\n          <div class=\"elementor-widget-wrap\" style=\"display:flex; flex-flow:column;\">\r\n              <div class=\"atividadesContainerSingleImage elementor-element elementor-element-3df9721 elementor-widget elementor-widget-image\" data-id=\"3df9721\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n        <div class=\"preco\">\r\n        60.00\u20ac\r\n      <\/div>\r\n        <div class=\"elementor-widget-container\">\r\n            <div class=\"elementor-image\">\r\n              <img decoding=\"async\" src=\"https:\/\/ocidentaladventures.pt\/wp-content\/uploads\/2022\/09\/IMG_2584-scaled.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" >\t\t\t\t\t\t\t\t\t\t\t\r\n            <\/div>\r\n        <\/div>\r\n      <\/div>\r\n              <div class=\"elementor-element elementor-element-bc89a85 elementor-widget elementor-widget-penci-fancy_heading\" data-id=\"bc89a85\" data-element_type=\"widget\" data-widget_type=\"penci-fancy_heading.default\" style=\"flex-grow:1;\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"penci-fancy-heading penci-heading-text-left\">\r\n                      <div class=\"penci-fancy-heading-inner\">\r\n                          <h2 class=\"penci-heading-title\">Hiking Costa Oeste<\/h2>\r\n                          <div class=\"penci-heading-content entry-content\">\r\n                            En este paseo que tendr\u00e1 inico en la Freguesia do Lajedo y termino en la&hellip;\r\n                          <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"elementor-element elementor-element-9b598ac elementor-align-left elementor-widget elementor-widget-button\" data-id=\"9b598ac\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n                <div class=\"elementor-widget-container\">\r\n                    <div class=\"elementor-button-wrapper\">\r\n                      <a href=\"https:\/\/ocidentaladventures.pt\/es\/atividade\/hiking\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\r\n                      <span class=\"elementor-button-content-wrapper\">\r\n                      <span class=\"elementor-button-text\">Reservar<\/span>\r\n                      <\/span>\r\n                      <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n              <\/div>\r\n          <\/div>\r\n        <\/div>\r\n    <\/div>\r\n                          <\/div>\r\n                      <\/div>\r\n                    <\/section>\r\n                <\/div>\r\n              <\/div>\r\n          <\/div>\r\n        <\/div>\r\n    <\/div>\r\n  <\/section><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-e78c791 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e78c791\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e538a2\" data-id=\"9e538a2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ad334c elementor-widget elementor-widget-shortcode\" data-id=\"1ad334c\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><section class=\"penci-section penci-dmcheck penci-elbg-activate penci-elbg-img penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-79cb22f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79cb22f\" style=\"background-image:url()\">\r\n    <div class=\"elementor-background-overlay\"><\/div>\r\n    <div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\r\n      <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\r\n          <path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"><\/path>\r\n          <path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"><\/path>\r\n          <path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"><\/path>\r\n      <\/svg>\r\n    <\/div>\r\n    <div class=\"elementor-container elementor-column-gap-no\">\r\n      <div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b95728\" data-id=\"8b95728\" data-element_type=\"column\">\r\n          <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n            <div class=\"elementor-element elementor-element-f31e433 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f31e433\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\r\n                <div class=\"elementor-widget-container\">\r\n                  <div class=\"elementor-icon-wrapper\">\r\n                      <div class=\"elementor-icon\">\r\n                        <i aria-hidden=\"true\" class=\"fas fa-globe\"><\/i>\t\t\t\r\n                      <\/div>\r\n                  <\/div>\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"elementor-element elementor-element-42aa98b elementor-widget elementor-widget-penci-fancy_heading\" data-id=\"42aa98b\" data-element_type=\"widget\" data-widget_type=\"penci-fancy_heading.default\">\r\n                <div class=\"elementor-widget-container\">\r\n                  <div class=\"penci-fancy-heading penci-heading-text-center\">\r\n                      <div class=\"penci-fancy-heading-inner\">\r\n                        <h2 class=\"penci-heading-title\"><span class=\"inner-tit\"><\/span><\/h2>\r\n                        <div class=\"penci-heading-content entry-content\">\r\n                        \r\n                        <\/div>\r\n                      <\/div>\r\n                  <\/div>\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"elementor-element elementor-element-b166c8b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b166c8b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n                <div class=\"elementor-widget-container\">\r\n                  <div class=\"elementor-button-wrapper\">\r\n                      <a href=\"https:\/\/ocidentaladventures.pt\/ilha-das-flores-acores-contactos\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\r\n                      <span class=\"elementor-button-content-wrapper\">\r\n                      <span class=\"elementor-button-text\">Cont\u00e1ctenos<\/span>\r\n                      <\/span>\r\n                      <\/a>\r\n                  <\/div>\r\n                <\/div>\r\n            <\/div>\r\n          <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/section><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Actividades Actividades Actividades Actividades Actividades Activit\u00e9s Activit\u00e9s activities activities activities activities activities<\/p>\n","protected":false},"author":1,"featured_media":920,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-fullwidth.php","meta":{"footnotes":""},"class_list":["post-467","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Canyoning, Hiking y Tours en la Isla de las Flores, Azores<\/title>\n<meta name=\"description\" content=\"En la isla de las Flores garantizamos la mejor diversi\u00f3n para tus vacaciones. \u00a1Habla con nosotros y prep\u00e1rate para muchas aventuras!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ocidentaladventures.pt\/es\/actividades\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canyoning, Hiking y Tours en la Isla de las Flores, Azores\" \/>\n<meta property=\"og:description\" content=\"En la isla de las Flores garantizamos la mejor diversi\u00f3n para tus vacaciones. \u00a1Habla con nosotros y prep\u00e1rate para muchas aventuras!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ocidentaladventures.pt\/es\/actividades\/\" \/>\n<meta property=\"og:site_name\" content=\"Ocidental Adventures\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-20T16:29:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ocidentaladventures.pt\/wp-content\/uploads\/2023\/01\/A7I03694-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ocidentaladventures.pt\/es\/actividades\/\",\"url\":\"https:\/\/ocidentaladventures.pt\/es\/actividades\/\",\"name\":\"Canyoning, Hiking y Tours en la Isla de las Flores, Azores\",\"isPartOf\":{\"@id\":\"https:\/\/ocidentaladventures.pt\/#website\"},\"datePublished\":\"2019-10-18T08:33:41+00:00\",\"dateModified\":\"2023-01-20T16:29:03+00:00\",\"description\":\"En la isla de las Flores garantizamos la mejor diversi\u00f3n para tus vacaciones. \u00a1Habla con nosotros y prep\u00e1rate para muchas aventuras!\",\"breadcrumb\":{\"@id\":\"https:\/\/ocidentaladventures.pt\/es\/actividades\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ocidentaladventures.pt\/es\/actividades\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ocidentaladventures.pt\/es\/actividades\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ocidentaladventures.pt\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actividades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ocidentaladventures.pt\/#website\",\"url\":\"https:\/\/ocidentaladventures.pt\/\",\"name\":\"Ocidental Adventures\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ocidentaladventures.pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canyoning, Hiking y Tours en la Isla de las Flores, Azores","description":"En la isla de las Flores garantizamos la mejor diversi\u00f3n para tus vacaciones. \u00a1Habla con nosotros y prep\u00e1rate para muchas aventuras!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ocidentaladventures.pt\/es\/actividades\/","og_locale":"es_ES","og_type":"article","og_title":"Canyoning, Hiking y Tours en la Isla de las Flores, Azores","og_description":"En la isla de las Flores garantizamos la mejor diversi\u00f3n para tus vacaciones. \u00a1Habla con nosotros y prep\u00e1rate para muchas aventuras!","og_url":"https:\/\/ocidentaladventures.pt\/es\/actividades\/","og_site_name":"Ocidental Adventures","article_modified_time":"2023-01-20T16:29:03+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/ocidentaladventures.pt\/wp-content\/uploads\/2023\/01\/A7I03694-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ocidentaladventures.pt\/es\/actividades\/","url":"https:\/\/ocidentaladventures.pt\/es\/actividades\/","name":"Canyoning, Hiking y Tours en la Isla de las Flores, Azores","isPartOf":{"@id":"https:\/\/ocidentaladventures.pt\/#website"},"datePublished":"2019-10-18T08:33:41+00:00","dateModified":"2023-01-20T16:29:03+00:00","description":"En la isla de las Flores garantizamos la mejor diversi\u00f3n para tus vacaciones. \u00a1Habla con nosotros y prep\u00e1rate para muchas aventuras!","breadcrumb":{"@id":"https:\/\/ocidentaladventures.pt\/es\/actividades\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ocidentaladventures.pt\/es\/actividades\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ocidentaladventures.pt\/es\/actividades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ocidentaladventures.pt\/es\/"},{"@type":"ListItem","position":2,"name":"Actividades"}]},{"@type":"WebSite","@id":"https:\/\/ocidentaladventures.pt\/#website","url":"https:\/\/ocidentaladventures.pt\/","name":"Ocidental Adventures","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ocidentaladventures.pt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/ocidentaladventures.pt\/es\/wp-json\/wp\/v2\/pages\/467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ocidentaladventures.pt\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ocidentaladventures.pt\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ocidentaladventures.pt\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ocidentaladventures.pt\/es\/wp-json\/wp\/v2\/comments?post=467"}],"version-history":[{"count":3,"href":"https:\/\/ocidentaladventures.pt\/es\/wp-json\/wp\/v2\/pages\/467\/revisions"}],"predecessor-version":[{"id":1367,"href":"https:\/\/ocidentaladventures.pt\/es\/wp-json\/wp\/v2\/pages\/467\/revisions\/1367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ocidentaladventures.pt\/es\/wp-json\/wp\/v2\/media\/920"}],"wp:attachment":[{"href":"https:\/\/ocidentaladventures.pt\/es\/wp-json\/wp\/v2\/media?parent=467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}